{"id":5712,"date":"2025-07-25T14:56:35","date_gmt":"2025-07-25T19:56:35","guid":{"rendered":"https:\/\/bac-cia.com\/?page_id=5712"},"modified":"2025-11-04T15:33:00","modified_gmt":"2025-11-04T20:33:00","slug":"customers","status":"publish","type":"page","link":"https:\/\/bac-cia.com\/en\/clientes\/","title":{"rendered":"CUSTOMERS"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"5712\" class=\"elementor elementor-5712\" data-elementor-post-type=\"page\">\n\t\t\t\t<div data-animation-type=\"block\" class=\"elementor-element elementor-element-4d25302e elementor-hidden-tablet elementor-hidden-mobile e-con-full e-flex sc_layouts_column_icons_position_left animation_type_block elementor-invisible e-con e-parent\" data-id=\"4d25302e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;ta_fadein&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-2bbb62db e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"2bbb62db\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-62e123d5 sc_fly_static elementor-widget elementor-widget-trx_sc_layouts_logo\" data-id=\"62e123d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_layouts_logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"https:\/\/bac-cia.com\/en\/\"\n\t\tclass=\"sc_layouts_logo sc_layouts_logo_default trx_addons_inline_1000612393\" ><img fetchpriority=\"high\" class=\"logo_image\"\n\t\t\t\t\tsrc=\"\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/cropped-logowebnormal.png\"\n\t\t\t\t\t\t\t\t\t\t\tsrcset=\"\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/cropped-logowebnormal.png 2x\"\n\t\t\t\t\t\t\t\t\t\t\talt=\"BAC &amp; Co.\" width=\"500\" height=\"240\"><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-11da0961 e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"11da0961\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a40c444 trx-addons-ham-slide trx-addons-dropdown-icon-fixed trx-addons-nav-hor trx-addons-nav-none trx-addons-slide-menu-effect-slide trx-addons-ver-hamburger-menu-left trx-addons-mobile-menu-align-flex-start sc_fly_static elementor-widget elementor-widget-trx_elm_nav_menu\" data-id=\"5a40c444\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;fas fa-chevron-down&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;submenu_item_icon&quot;:{&quot;value&quot;:&quot;fas fa-chevron-right&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"trx_elm_nav_menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-settings=\"{&quot;breakpoint&quot;:1279,&quot;mobileLayout&quot;:&quot;slide&quot;,&quot;mainLayout&quot;:&quot;hor&quot;,&quot;stretchDropdown&quot;:false,&quot;hoverEffect&quot;:&quot;&quot;,&quot;submenuEvent&quot;:&quot;hover&quot;,&quot;submenuTrigger&quot;:null,&quot;closeAfterClick&quot;:false}\" class=\"trx-addons-nav-widget-container trx-addons-nav-pointer-none\">\n\t\t\t<div class=\"trx-addons-ver-inner-container\">\n\t\t\t\t<div class=\"trx-addons-hamburger-toggle trx-addons-mobile-menu-icon\" role=\"button\" aria-label=\"Toggle Menu\">\n\t\t\t\t\t<span class=\"trx-addons-toggle-text\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bars\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M16 132h416c8.837 0 16-7.163 16-16V76c0-8.837-7.163-16-16-16H16C7.163 60 0 67.163 0 76v40c0 8.837 7.163 16 16 16zm0 160h416c8.837 0 16-7.163 16-16v-40c0-8.837-7.163-16-16-16H16c-8.837 0-16 7.163-16 16v40c0 8.837 7.163 16 16 16zm0 160h416c8.837 0 16-7.163 16-16v-40c0-8.837-7.163-16-16-16H16c-8.837 0-16 7.163-16 16v40c0 8.837 7.163 16 16 16z\"><\/path><\/svg>Menu\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"trx-addons-toggle-close\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-times\" viewbox=\"0 0 352 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M242.72 256l100.07-100.07c12.28-12.28 12.28-32.19 0-44.48l-22.24-22.24c-12.28-12.28-32.19-12.28-44.48 0L176 189.28 75.93 89.21c-12.28-12.28-32.19-12.28-44.48 0L9.21 111.45c-12.28 12.28-12.28 32.19 0 44.48L109.28 256 9.21 356.07c-12.28 12.28-12.28 32.19 0 44.48l22.24 22.24c12.28 12.28 32.2 12.28 44.48 0L176 322.72l100.07 100.07c12.28 12.28 32.2 12.28 44.48 0l22.24-22.24c12.28-12.28 12.28-32.19 0-44.48L242.72 256z\"><\/path><\/svg>Close\t\t\t\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"trx-addons-nav-menu-container trx-addons-nav-default\">\n\t\t\t\t\t\t\t<ul id=\"menu-main-menu\" class=\"trx-addons-nav-menu trx-addons-main-nav-menu\"><li id=\"trx-addons-nav-menu-item-5752\" class=\"trp-language-switcher-container trp-menu-ls-item trp-menu-ls-desktop current-language-menu-item menu-item menu-item-type-post_type menu-item-object-language_switcher menu-item-has-children trx-addons-nav-menu-item\"><a href=\"https:\/\/bac-cia.com\/en\/wp-json\/wp\/v2\/pages\/5712\" class=\"trx-addons-menu-link trx-addons-menu-link-parent\"><span class=\"trx-addons-menu-link-text\"><span class=\"trp-menu-ls-label\" data-no-translation title=\"EN\"><span class=\"trp-ls-language-name\">EN<\/span><\/span><span class=\"trx-addons-dropdown-icon trx-addons-icon\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><\/span><\/a>\n<ul class=\"trx-addons-submenu\"><li id=\"trx-addons-nav-menu-item-5755\" class=\"trp-language-switcher-container trp-menu-ls-item trp-menu-ls-desktop menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item trx-addons-nav-menu-item trx-addons-submenu-item\"><a href=\"https:\/\/bac-cia.com\/en\/wp-json\/wp\/v2\/pages\/5712\" class=\"trx-addons-menu-link trx-addons-submenu-link\"><span class=\"trx-addons-menu-link-text trx-addons-submenu-link-text\"><span class=\"trp-menu-ls-label\" data-no-translation title=\"ES\"><span class=\"trp-ls-language-name\">ES<\/span><\/span><\/span><\/a><\/li><li id=\"trx-addons-nav-menu-item-5753\" class=\"trp-language-switcher-container trp-menu-ls-item trp-menu-ls-desktop menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item trx-addons-nav-menu-item trx-addons-submenu-item\"><a href=\"https:\/\/bac-cia.com\/en\/wp-json\/wp\/v2\/pages\/5712\" class=\"trx-addons-menu-link trx-addons-submenu-link\"><span class=\"trx-addons-menu-link-text trx-addons-submenu-link-text\"><span class=\"trp-menu-ls-label\" data-no-translation title=\"FR\"><span class=\"trp-ls-language-name\">FR<\/span><\/span><\/span><\/a><\/li><\/ul>\n<\/li><li id=\"trx-addons-nav-menu-item-1116\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home trx-addons-nav-menu-item\"><a href=\"https:\/\/bac-cia.com\/en\/\" class=\"trx-addons-menu-link trx-addons-menu-link-parent\"><span class=\"trx-addons-menu-link-text\">HOME<\/span><\/a><\/li><li id=\"trx-addons-nav-menu-item-5709\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children trx-addons-nav-menu-item\"><a href=\"#\" class=\"trx-addons-menu-link trx-addons-menu-link-parent\"><span class=\"trx-addons-menu-link-text\">WE<span class=\"trx-addons-dropdown-icon trx-addons-icon\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><\/span><\/a>\n<ul class=\"trx-addons-submenu\"><li id=\"trx-addons-nav-menu-item-4002\" class=\"menu-item menu-item-type-post_type menu-item-object-page trx-addons-nav-menu-item trx-addons-submenu-item\"><a href=\"https:\/\/bac-cia.com\/en\/equipo\/\" class=\"trx-addons-menu-link trx-addons-submenu-link\"><span class=\"trx-addons-menu-link-text trx-addons-submenu-link-text\">TEAM<\/span><\/a><\/li><li id=\"trx-addons-nav-menu-item-4004\" class=\"menu-item menu-item-type-post_type menu-item-object-page trx-addons-nav-menu-item trx-addons-submenu-item\"><a href=\"https:\/\/bac-cia.com\/en\/servicios\/\" class=\"trx-addons-menu-link trx-addons-submenu-link\"><span class=\"trx-addons-menu-link-text trx-addons-submenu-link-text\">SERVICES<\/span><\/a><\/li><li id=\"trx-addons-nav-menu-item-5714\" class=\"menu-item menu-item-type-post_type menu-item-object-page trx-addons-nav-menu-item trx-addons-submenu-item\"><a href=\"https:\/\/bac-cia.com\/en\/clientes\/\" class=\"trx-addons-menu-link trx-addons-submenu-link\"><span class=\"trx-addons-menu-link-text trx-addons-submenu-link-text\">CUSTOMERS<\/span><\/a><\/li><li id=\"trx-addons-nav-menu-item-6327\" class=\"menu-item menu-item-type-post_type menu-item-object-page trx-addons-nav-menu-item trx-addons-submenu-item\"><a href=\"https:\/\/bac-cia.com\/en\/barras-y-asociaciones\/\" class=\"trx-addons-menu-link trx-addons-submenu-link\"><span class=\"trx-addons-menu-link-text trx-addons-submenu-link-text\">BARS AND ASSOCIATIONS<\/span><\/a><\/li><li id=\"trx-addons-nav-menu-item-5710\" class=\"menu-item menu-item-type-post_type menu-item-object-page trx-addons-nav-menu-item trx-addons-submenu-item\"><a href=\"https:\/\/bac-cia.com\/en\/comunidad-suiza\/\" class=\"trx-addons-menu-link trx-addons-submenu-link\"><span class=\"trx-addons-menu-link-text trx-addons-submenu-link-text\">SWISS COMMUNITY<\/span><\/a><\/li><\/ul>\n<\/li><li id=\"trx-addons-nav-menu-item-5711\" class=\"menu-item menu-item-type-post_type menu-item-object-page trx-addons-nav-menu-item\"><a href=\"https:\/\/bac-cia.com\/en\/noticias\/\" class=\"trx-addons-menu-link trx-addons-menu-link-parent\"><span class=\"trx-addons-menu-link-text\">NEWS<\/span><\/a><\/li><li id=\"trx-addons-nav-menu-item-5343\" class=\"menu-item menu-item-type-post_type menu-item-object-page trx-addons-nav-menu-item\"><a href=\"https:\/\/bac-cia.com\/en\/contacto\/\" class=\"trx-addons-menu-link trx-addons-menu-link-parent\"><span class=\"trx-addons-menu-link-text\">CONTACT<\/span><\/a><\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"trx-addons-nav-slide-overlay\"><\/div>\n\t\t\t\t\t<div class=\"trx-addons-mobile-menu-outer-container\">\n\t\t\t\t\t\t<div class=\"trx-addons-mobile-menu-close\" role=\"button\" aria-label=\"Close Menu\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-times\" viewbox=\"0 0 352 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M242.72 256l100.07-100.07c12.28-12.28 12.28-32.19 0-44.48l-22.24-22.24c-12.28-12.28-32.19-12.28-44.48 0L176 189.28 75.93 89.21c-12.28-12.28-32.19-12.28-44.48 0L9.21 111.45c-12.28 12.28-12.28 32.19 0 44.48L109.28 256 9.21 356.07c-12.28 12.28-12.28 32.19 0 44.48l22.24 22.24c12.28 12.28 32.2 12.28 44.48 0L176 322.72l100.07 100.07c12.28 12.28 32.2 12.28 44.48 0l22.24-22.24c12.28-12.28 12.28-32.19 0-44.48L242.72 256z\"><\/path><\/svg>\t\t\t\t\t\t\t\t<span class=\"trx-addons-toggle-close\">Close<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"trx-addons-mobile-menu-container\">\n\t\t\t\t\t\t<ul id=\"menu-main-menu-7703\" class=\"trx-addons-mobile-menu trx-addons-main-mobile-menu trx-addons-main-nav-menu\"><li id=\"trx-addons-nav-menu-item-57521\" class=\"trp-language-switcher-container trp-menu-ls-item trp-menu-ls-desktop current-language-menu-item menu-item menu-item-type-post_type menu-item-object-language_switcher menu-item-has-children trx-addons-nav-menu-item\"><a href=\"https:\/\/bac-cia.com\/en\/wp-json\/wp\/v2\/pages\/5712\" class=\"trx-addons-menu-link trx-addons-menu-link-parent\"><span class=\"trx-addons-menu-link-text\"><span class=\"trp-menu-ls-label\" data-no-translation title=\"EN\"><span class=\"trp-ls-language-name\">EN<\/span><\/span><span class=\"trx-addons-dropdown-icon trx-addons-icon\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><\/span><\/a>\n<ul class=\"trx-addons-submenu\"><li id=\"trx-addons-nav-menu-item-57552\" class=\"trp-language-switcher-container trp-menu-ls-item trp-menu-ls-desktop menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item trx-addons-nav-menu-item trx-addons-submenu-item\"><a href=\"https:\/\/bac-cia.com\/en\/wp-json\/wp\/v2\/pages\/5712\" class=\"trx-addons-menu-link trx-addons-submenu-link\"><span class=\"trx-addons-menu-link-text trx-addons-submenu-link-text\"><span class=\"trp-menu-ls-label\" data-no-translation title=\"ES\"><span class=\"trp-ls-language-name\">ES<\/span><\/span><\/span><\/a><\/li><li id=\"trx-addons-nav-menu-item-57533\" class=\"trp-language-switcher-container trp-menu-ls-item trp-menu-ls-desktop menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item trx-addons-nav-menu-item trx-addons-submenu-item\"><a href=\"https:\/\/bac-cia.com\/en\/wp-json\/wp\/v2\/pages\/5712\" class=\"trx-addons-menu-link trx-addons-submenu-link\"><span class=\"trx-addons-menu-link-text trx-addons-submenu-link-text\"><span class=\"trp-menu-ls-label\" data-no-translation title=\"FR\"><span class=\"trp-ls-language-name\">FR<\/span><\/span><\/span><\/a><\/li><\/ul>\n<\/li><li id=\"trx-addons-nav-menu-item-11164\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home trx-addons-nav-menu-item\"><a href=\"https:\/\/bac-cia.com\/en\/\" class=\"trx-addons-menu-link trx-addons-menu-link-parent\"><span class=\"trx-addons-menu-link-text\">HOME<\/span><\/a><\/li><li id=\"trx-addons-nav-menu-item-57095\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children trx-addons-nav-menu-item\"><a href=\"#\" class=\"trx-addons-menu-link trx-addons-menu-link-parent\"><span class=\"trx-addons-menu-link-text\">WE<span class=\"trx-addons-dropdown-icon trx-addons-icon\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><\/span><\/a>\n<ul class=\"trx-addons-submenu\"><li id=\"trx-addons-nav-menu-item-40026\" class=\"menu-item menu-item-type-post_type menu-item-object-page trx-addons-nav-menu-item trx-addons-submenu-item\"><a href=\"https:\/\/bac-cia.com\/en\/equipo\/\" class=\"trx-addons-menu-link trx-addons-submenu-link\"><span class=\"trx-addons-menu-link-text trx-addons-submenu-link-text\">TEAM<\/span><\/a><\/li><li id=\"trx-addons-nav-menu-item-40047\" class=\"menu-item menu-item-type-post_type menu-item-object-page trx-addons-nav-menu-item trx-addons-submenu-item\"><a href=\"https:\/\/bac-cia.com\/en\/servicios\/\" class=\"trx-addons-menu-link trx-addons-submenu-link\"><span class=\"trx-addons-menu-link-text trx-addons-submenu-link-text\">SERVICES<\/span><\/a><\/li><li id=\"trx-addons-nav-menu-item-57148\" class=\"menu-item menu-item-type-post_type menu-item-object-page trx-addons-nav-menu-item trx-addons-submenu-item\"><a href=\"https:\/\/bac-cia.com\/en\/clientes\/\" class=\"trx-addons-menu-link trx-addons-submenu-link\"><span class=\"trx-addons-menu-link-text trx-addons-submenu-link-text\">CUSTOMERS<\/span><\/a><\/li><li id=\"trx-addons-nav-menu-item-63279\" class=\"menu-item menu-item-type-post_type menu-item-object-page trx-addons-nav-menu-item trx-addons-submenu-item\"><a href=\"https:\/\/bac-cia.com\/en\/barras-y-asociaciones\/\" class=\"trx-addons-menu-link trx-addons-submenu-link\"><span class=\"trx-addons-menu-link-text trx-addons-submenu-link-text\">BARS AND ASSOCIATIONS<\/span><\/a><\/li><li id=\"trx-addons-nav-menu-item-571010\" class=\"menu-item menu-item-type-post_type menu-item-object-page trx-addons-nav-menu-item trx-addons-submenu-item\"><a href=\"https:\/\/bac-cia.com\/en\/comunidad-suiza\/\" class=\"trx-addons-menu-link trx-addons-submenu-link\"><span class=\"trx-addons-menu-link-text trx-addons-submenu-link-text\">SWISS COMMUNITY<\/span><\/a><\/li><\/ul>\n<\/li><li id=\"trx-addons-nav-menu-item-571111\" class=\"menu-item menu-item-type-post_type menu-item-object-page trx-addons-nav-menu-item\"><a href=\"https:\/\/bac-cia.com\/en\/noticias\/\" class=\"trx-addons-menu-link trx-addons-menu-link-parent\"><span class=\"trx-addons-menu-link-text\">NEWS<\/span><\/a><\/li><li id=\"trx-addons-nav-menu-item-534312\" class=\"menu-item menu-item-type-post_type menu-item-object-page trx-addons-nav-menu-item\"><a href=\"https:\/\/bac-cia.com\/en\/contacto\/\" class=\"trx-addons-menu-link trx-addons-menu-link-parent\"><span class=\"trx-addons-menu-link-text\">CONTACT<\/span><\/a><\/li><\/ul>\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7197b34d sc_fly_static elementor-widget elementor-widget-button\" data-id=\"7197b34d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/bac-cia.com\/en\/access\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACCESS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-54ccbf1c elementor-hidden-desktop e-flex e-con-boxed sc_layouts_column_icons_position_left e-con e-parent\" data-id=\"54ccbf1c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-812a300 e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"812a300\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c386456 sc_fly_static elementor-widget elementor-widget-trx_sc_layouts_logo\" data-id=\"2c386456\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_layouts_logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"https:\/\/bac-cia.com\/en\/\"\n\t\tclass=\"sc_layouts_logo sc_layouts_logo_default trx_addons_inline_25386980\" ><img fetchpriority=\"high\" class=\"logo_image\"\n\t\t\t\t\tsrc=\"\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/cropped-logowebnormal.png\"\n\t\t\t\t\t\t\t\t\t\t\tsrcset=\"\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/cropped-logowebnormal.png 2x\"\n\t\t\t\t\t\t\t\t\t\t\talt=\"BAC &amp; Co.\" width=\"500\" height=\"240\"><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d19dc12 e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"3d19dc12\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-66728a93 trx-addons-nav-slide trx-addons-ver-hamburger-menu-right trx-addons-slide-menu-effect-slide trx-addons-mobile-menu-align-flex-start trx-addons-dropdown-icon-inline sc_fly_static elementor-widget elementor-widget-trx_elm_nav_menu\" data-id=\"66728a93\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;fas fa-chevron-down&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;submenu_item_icon&quot;:{&quot;value&quot;:&quot;fas fa-chevron-down&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"trx_elm_nav_menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-settings=\"{&quot;breakpoint&quot;:1025,&quot;mobileLayout&quot;:null,&quot;mainLayout&quot;:&quot;slide&quot;,&quot;stretchDropdown&quot;:false,&quot;hoverEffect&quot;:&quot;&quot;,&quot;submenuEvent&quot;:null,&quot;submenuTrigger&quot;:null,&quot;closeAfterClick&quot;:false}\" class=\"trx-addons-nav-widget-container trx-addons-nav-pointer-none\" style=\"visibility:hidden; opacity:0;\">\n\t\t\t<div class=\"trx-addons-ver-inner-container\">\n\t\t\t\t<div class=\"trx-addons-hamburger-toggle trx-addons-mobile-menu-icon\" role=\"button\" aria-label=\"Toggle Menu\">\n\t\t\t\t\t<span class=\"trx-addons-toggle-text\">\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 23.4 15.4\"><g transform=\"translate(-0.3 -0.3)\"><path d=\"M23,1.7H1A.7.7,0,0,1,1,.3H23a.7.7,0,1,1,0,1.4Z\"><\/path><path d=\"M23,8.7H1A.7.7,0,1,1,1,7.3H23a.7.7,0,1,1,0,1.4Z\"><\/path><path d=\"M17,15.7H1a.7.7,0,1,1,0-1.4H17a.7.7,0,1,1,0,1.4Z\"><\/path><\/g><\/svg>\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"trx-addons-toggle-close\">\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\"><path d=\"M3.54038 3.54067C3.79422 3.28683 4.20578 3.28683 4.45962 3.54067L20.2342 19.3152C20.488 19.5691 20.488 19.9806 20.2342 20.2345C19.9803 20.4883 19.5688 20.4883 19.3149 20.2345L3.54038 4.45991C3.28654 4.20607 3.28654 3.79451 3.54038 3.54067Z\"><\/path><path d=\"M3.76431 20.4596C3.51047 20.2058 3.51047 19.7942 3.76431 19.5404L19.5389 3.76582C19.7927 3.51198 20.2043 3.51198 20.4581 3.76582C20.7119 4.01966 20.7119 4.43122 20.4581 4.68506L4.68355 20.4596C4.4297 20.7135 4.01815 20.7135 3.76431 20.4596Z\"><\/path><\/svg>\t\t\t\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"trx-addons-nav-slide-overlay\"><\/div>\n\t\t\t\t\t<div class=\"trx-addons-mobile-menu-outer-container\">\n\t\t\t\t\t\t<div class=\"trx-addons-mobile-menu-close\" role=\"button\" aria-label=\"Close Menu\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\"><path d=\"M3.54038 3.54067C3.79422 3.28683 4.20578 3.28683 4.45962 3.54067L20.2342 19.3152C20.488 19.5691 20.488 19.9806 20.2342 20.2345C19.9803 20.4883 19.5688 20.4883 19.3149 20.2345L3.54038 4.45991C3.28654 4.20607 3.28654 3.79451 3.54038 3.54067Z\"><\/path><path d=\"M3.76431 20.4596C3.51047 20.2058 3.51047 19.7942 3.76431 19.5404L19.5389 3.76582C19.7927 3.51198 20.2043 3.51198 20.4581 3.76582C20.7119 4.01966 20.7119 4.43122 20.4581 4.68506L4.68355 20.4596C4.4297 20.7135 4.01815 20.7135 3.76431 20.4596Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"trx-addons-mobile-menu-container\">\n\t\t\t\t\t\t<ul id=\"menu-main-menu-1-5516\" class=\"trx-addons-mobile-menu trx-addons-main-mobile-menu trx-addons-main-nav-menu\"><li class=\"trp-language-switcher-container trp-menu-ls-item trp-menu-ls-desktop current-language-menu-item menu-item menu-item-type-post_type menu-item-object-language_switcher menu-item-has-children trx-addons-nav-menu-item\"><a href=\"https:\/\/bac-cia.com\/en\/wp-json\/wp\/v2\/pages\/5712\" data-e-disable-page-transition=\"true\" class=\"trx-addons-menu-link trx-addons-menu-link-parent\"><span class=\"trx-addons-menu-link-text\"><span class=\"trp-menu-ls-label\" data-no-translation title=\"EN\"><span class=\"trp-ls-language-name\">EN<\/span><\/span><span class=\"trx-addons-dropdown-icon trx-addons-icon\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><\/span><\/a>\n<ul class=\"trx-addons-submenu\"><li class=\"trp-language-switcher-container trp-menu-ls-item trp-menu-ls-desktop menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item trx-addons-nav-menu-item trx-addons-submenu-item\"><a href=\"https:\/\/bac-cia.com\/en\/wp-json\/wp\/v2\/pages\/5712\" class=\"trx-addons-menu-link trx-addons-submenu-link\"><span class=\"trx-addons-menu-link-text trx-addons-submenu-link-text\"><span class=\"trp-menu-ls-label\" data-no-translation title=\"ES\"><span class=\"trp-ls-language-name\">ES<\/span><\/span><\/span><\/a><\/li><li class=\"trp-language-switcher-container trp-menu-ls-item trp-menu-ls-desktop menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item trx-addons-nav-menu-item trx-addons-submenu-item\"><a href=\"https:\/\/bac-cia.com\/en\/wp-json\/wp\/v2\/pages\/5712\" class=\"trx-addons-menu-link trx-addons-submenu-link\"><span class=\"trx-addons-menu-link-text trx-addons-submenu-link-text\"><span class=\"trp-menu-ls-label\" data-no-translation title=\"FR\"><span class=\"trp-ls-language-name\">FR<\/span><\/span><\/span><\/a><\/li><\/ul>\n<\/li><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home trx-addons-nav-menu-item\"><a href=\"https:\/\/bac-cia.com\/en\/\" class=\"trx-addons-menu-link trx-addons-menu-link-parent\"><span class=\"trx-addons-menu-link-text\">HOME<\/span><\/a><\/li><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children trx-addons-nav-menu-item\"><a href=\"#\" data-e-disable-page-transition=\"true\" class=\"trx-addons-menu-link trx-addons-menu-link-parent\"><span class=\"trx-addons-menu-link-text\">WE<span class=\"trx-addons-dropdown-icon trx-addons-icon\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><\/span><\/a>\n<ul class=\"trx-addons-submenu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page trx-addons-nav-menu-item trx-addons-submenu-item\"><a href=\"https:\/\/bac-cia.com\/en\/equipo\/\" class=\"trx-addons-menu-link trx-addons-submenu-link\"><span class=\"trx-addons-menu-link-text trx-addons-submenu-link-text\">TEAM<\/span><\/a><\/li><li class=\"menu-item menu-item-type-post_type menu-item-object-page trx-addons-nav-menu-item trx-addons-submenu-item\"><a href=\"https:\/\/bac-cia.com\/en\/servicios\/\" class=\"trx-addons-menu-link trx-addons-submenu-link\"><span class=\"trx-addons-menu-link-text trx-addons-submenu-link-text\">SERVICES<\/span><\/a><\/li><li class=\"menu-item menu-item-type-post_type menu-item-object-page trx-addons-nav-menu-item trx-addons-submenu-item\"><a href=\"https:\/\/bac-cia.com\/en\/clientes\/\" class=\"trx-addons-menu-link trx-addons-submenu-link\"><span class=\"trx-addons-menu-link-text trx-addons-submenu-link-text\">CUSTOMERS<\/span><\/a><\/li><li class=\"menu-item menu-item-type-post_type menu-item-object-page trx-addons-nav-menu-item trx-addons-submenu-item\"><a href=\"https:\/\/bac-cia.com\/en\/barras-y-asociaciones\/\" class=\"trx-addons-menu-link trx-addons-submenu-link\"><span class=\"trx-addons-menu-link-text trx-addons-submenu-link-text\">BARS AND ASSOCIATIONS<\/span><\/a><\/li><li class=\"menu-item menu-item-type-post_type menu-item-object-page trx-addons-nav-menu-item trx-addons-submenu-item\"><a href=\"https:\/\/bac-cia.com\/en\/comunidad-suiza\/\" class=\"trx-addons-menu-link trx-addons-submenu-link\"><span class=\"trx-addons-menu-link-text trx-addons-submenu-link-text\">SWISS COMMUNITY<\/span><\/a><\/li><\/ul>\n<\/li><li class=\"menu-item menu-item-type-post_type menu-item-object-page trx-addons-nav-menu-item\"><a href=\"https:\/\/bac-cia.com\/en\/noticias\/\" class=\"trx-addons-menu-link trx-addons-menu-link-parent\"><span class=\"trx-addons-menu-link-text\">NEWS<\/span><\/a><\/li><li class=\"menu-item menu-item-type-post_type menu-item-object-page trx-addons-nav-menu-item\"><a href=\"https:\/\/bac-cia.com\/en\/contacto\/\" class=\"trx-addons-menu-link trx-addons-menu-link-parent\"><span class=\"trx-addons-menu-link-text\">CONTACT<\/span><\/a><\/li><\/ul>\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a74c749 e-flex e-con-boxed sc_layouts_column_icons_position_left e-con e-parent\" data-id=\"a74c749\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-62c07af sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"62c07af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"e-con-with-custom-width elementor-element elementor-element-03989f3 e-con-full e-flex sc_layouts_column_icons_position_left e-con e-parent\" data-id=\"03989f3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-7f08eed e-con-full sc_column_fixed e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"7f08eed\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div data-animation-type=\"block\" class=\"elementor-element elementor-element-cd7fe36 animation_type_block sc_fly_static elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"cd7fe36\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;ta_fadeinup&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">We promote our clients with a legal vision\n<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-animation-type=\"block\" class=\"elementor-element elementor-element-833e8c6 elementor-widget__width-initial animation_type_block sc_fly_static elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"833e8c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;ta_fadeinup&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Our Clients<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-animation-type=\"block\" class=\"elementor-element elementor-element-a9882dc elementor-widget__width-initial animation_type_block sc_fly_static elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"a9882dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;ta_fadeinup&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>At BAC &amp; Cia. we work with companies and institutions that demand excellence. Each logo represents a relationship built on results, integrity and shared vision.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-93ad7b7 e-grid e-con-full sc_layouts_column_icons_position_left e-con e-child\" data-id=\"93ad7b7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-05d7ac7 e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"05d7ac7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-59440d9 with-elementor-animation-grow e-transform sc_fly_static elementor-widget elementor-widget-image\" data-id=\"59440d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.3,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/jw-original.png\" class=\"elementor-animation-grow attachment-full size-full wp-image-6040\" alt=\"\" srcset=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/jw-original.png 500w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/jw-original-300x300.png 300w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/jw-original-150x150.png 150w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/jw-original-370x370.png 370w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/jw-original-90x90.png 90w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/jw-original-410x410.png 410w\" sizes=\"(max-width: 767px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b67817d e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"b67817d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8c1bd8c e-transform with-elementor-animation-grow sc_fly_static elementor-widget elementor-widget-image\" data-id=\"8c1bd8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.3,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/belmont-original.png\" class=\"elementor-animation-grow attachment-full size-full wp-image-6039\" alt=\"\" srcset=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/belmont-original.png 500w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/belmont-original-300x300.png 300w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/belmont-original-150x150.png 150w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/belmont-original-370x370.png 370w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/belmont-original-90x90.png 90w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/belmont-original-410x410.png 410w\" sizes=\"(max-width: 767px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3283041 e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"3283041\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4eb725e e-transform sc_fly_static elementor-widget elementor-widget-image\" data-id=\"4eb725e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.3,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/crown-original.png\" class=\"attachment-full size-full wp-image-6038\" alt=\"\" srcset=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/crown-original.png 500w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/crown-original-300x300.png 300w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/crown-original-150x150.png 150w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/crown-original-370x370.png 370w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/crown-original-90x90.png 90w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/crown-original-410x410.png 410w\" sizes=\"(max-width: 767px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ea76752 e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"ea76752\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3447652 e-transform sc_fly_static elementor-widget elementor-widget-image\" data-id=\"3447652\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.5,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/marriott-cancun-original.png\" class=\"attachment-full size-full wp-image-6049\" alt=\"\" srcset=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/marriott-cancun-original.png 500w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/marriott-cancun-original-300x300.png 300w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/marriott-cancun-original-150x150.png 150w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/marriott-cancun-original-370x370.png 370w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/marriott-cancun-original-90x90.png 90w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/marriott-cancun-original-410x410.png 410w\" sizes=\"(max-width: 767px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b54298d e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"b54298d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-907d382 e-transform sc_fly_static elementor-widget elementor-widget-image\" data-id=\"907d382\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.3,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/krystal-original.png\" class=\"attachment-full size-full wp-image-6036\" alt=\"\" srcset=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/krystal-original.png 500w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/krystal-original-300x300.png 300w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/krystal-original-150x150.png 150w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/krystal-original-370x370.png 370w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/krystal-original-90x90.png 90w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/krystal-original-410x410.png 410w\" sizes=\"(max-width: 767px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-20c7a40 e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"20c7a40\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db28fcd e-transform sc_fly_static elementor-widget elementor-widget-image\" data-id=\"db28fcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.3,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/krystal-grand-original.png\" class=\"attachment-full size-full wp-image-6035\" alt=\"\" srcset=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/krystal-grand-original.png 500w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/krystal-grand-original-300x300.png 300w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/krystal-grand-original-150x150.png 150w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/krystal-grand-original-370x370.png 370w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/krystal-grand-original-90x90.png 90w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/krystal-grand-original-410x410.png 410w\" sizes=\"(max-width: 767px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5968635 e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"5968635\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e727348 e-transform sc_fly_static elementor-widget elementor-widget-image\" data-id=\"e727348\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.3,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/costco-original.png\" class=\"attachment-full size-full wp-image-6034\" alt=\"\" srcset=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/costco-original.png 500w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/costco-original-300x300.png 300w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/costco-original-150x150.png 150w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/costco-original-370x370.png 370w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/costco-original-90x90.png 90w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/costco-original-410x410.png 410w\" sizes=\"(max-width: 767px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5fe57d4 e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"5fe57d4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0beb8a9 e-transform sc_fly_static elementor-widget elementor-widget-image\" data-id=\"0beb8a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.3,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/sensir-original-oscuro.png\" class=\"attachment-full size-full wp-image-6032\" alt=\"\" srcset=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/sensir-original-oscuro.png 500w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/sensir-original-oscuro-300x300.png 300w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/sensir-original-oscuro-150x150.png 150w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/sensir-original-oscuro-370x370.png 370w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/sensir-original-oscuro-90x90.png 90w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/sensir-original-oscuro-410x410.png 410w\" sizes=\"(max-width: 767px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c43db6d e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"c43db6d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-05262cc e-transform sc_fly_static elementor-widget elementor-widget-image\" data-id=\"05262cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.3,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/captain-original.png\" class=\"attachment-full size-full wp-image-6031\" alt=\"\" srcset=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/captain-original.png 500w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/captain-original-300x300.png 300w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/captain-original-150x150.png 150w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/captain-original-370x370.png 370w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/captain-original-90x90.png 90w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/captain-original-410x410.png 410w\" sizes=\"(max-width: 767px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fb073a9 e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"fb073a9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef24874 e-transform sc_fly_static elementor-widget elementor-widget-image\" data-id=\"ef24874\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.3,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/krystal-urban-original.png\" class=\"attachment-full size-full wp-image-6030\" alt=\"\" srcset=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/krystal-urban-original.png 500w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/krystal-urban-original-300x300.png 300w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/krystal-urban-original-150x150.png 150w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/krystal-urban-original-370x370.png 370w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/krystal-urban-original-90x90.png 90w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/krystal-urban-original-410x410.png 410w\" sizes=\"(max-width: 767px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-40469f6 e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"40469f6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8aa3b7a e-transform e-transform sc_fly_static elementor-widget elementor-widget-image\" data-id=\"8aa3b7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.3,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2560\" src=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/CA_LOGO__TEAL1-scaled.png\" class=\"attachment-full size-full wp-image-6282\" alt=\"\" srcset=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/CA_LOGO__TEAL1-scaled.png 2560w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/CA_LOGO__TEAL1-300x300.png 300w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/CA_LOGO__TEAL1-1024x1024.png 1024w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/CA_LOGO__TEAL1-150x150.png 150w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/CA_LOGO__TEAL1-768x768.png 768w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/CA_LOGO__TEAL1-1536x1536.png 1536w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/CA_LOGO__TEAL1-2048x2048.png 2048w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/CA_LOGO__TEAL1-370x370.png 370w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/CA_LOGO__TEAL1-90x90.png 90w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/CA_LOGO__TEAL1-924x924.png 924w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/CA_LOGO__TEAL1-410x410.png 410w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9a36315 e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"9a36315\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61415e8 e-transform sc_fly_static elementor-widget elementor-widget-image\" data-id=\"61415e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.3,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1764\" height=\"1764\" src=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/355735522_645786114243601_6516737698674333224_n.png\" class=\"attachment-full size-full wp-image-6283\" alt=\"\" srcset=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/355735522_645786114243601_6516737698674333224_n.png 1764w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/355735522_645786114243601_6516737698674333224_n-300x300.png 300w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/355735522_645786114243601_6516737698674333224_n-1024x1024.png 1024w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/355735522_645786114243601_6516737698674333224_n-150x150.png 150w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/355735522_645786114243601_6516737698674333224_n-768x768.png 768w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/355735522_645786114243601_6516737698674333224_n-1536x1536.png 1536w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/355735522_645786114243601_6516737698674333224_n-370x370.png 370w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/355735522_645786114243601_6516737698674333224_n-90x90.png 90w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/355735522_645786114243601_6516737698674333224_n-924x924.png 924w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/09\/355735522_645786114243601_6516737698674333224_n-410x410.png 410w\" sizes=\"(max-width: 1764px) 100vw, 1764px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7decbd4 e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"7decbd4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9390873 e-transform sc_fly_static elementor-widget elementor-widget-image\" data-id=\"9390873\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.3,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/Thermaflex-original.png\" class=\"attachment-full size-full wp-image-6027\" alt=\"\" srcset=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/Thermaflex-original.png 500w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/Thermaflex-original-300x300.png 300w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/Thermaflex-original-150x150.png 150w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/Thermaflex-original-370x370.png 370w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/Thermaflex-original-90x90.png 90w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/Thermaflex-original-410x410.png 410w\" sizes=\"(max-width: 767px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cefd14f e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"cefd14f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c1fb34 e-transform sc_fly_static elementor-widget elementor-widget-image\" data-id=\"4c1fb34\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.3,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/be-towers-original.png\" class=\"attachment-full size-full wp-image-6026\" alt=\"\" srcset=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/be-towers-original.png 500w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/be-towers-original-300x300.png 300w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/be-towers-original-150x150.png 150w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/be-towers-original-370x370.png 370w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/be-towers-original-90x90.png 90w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/be-towers-original-410x410.png 410w\" sizes=\"(max-width: 767px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e40ee54 e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"e40ee54\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f220de e-transform sc_fly_static elementor-widget elementor-widget-image\" data-id=\"1f220de\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.3,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/shark-original.png\" class=\"attachment-full size-full wp-image-6025\" alt=\"\" srcset=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/shark-original.png 500w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/shark-original-300x300.png 300w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/shark-original-150x150.png 150w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/shark-original-370x370.png 370w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/shark-original-90x90.png 90w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/shark-original-410x410.png 410w\" sizes=\"(max-width: 767px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-98f6b71 e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"98f6b71\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f3fd21 e-transform sc_fly_static elementor-widget elementor-widget-image\" data-id=\"9f3fd21\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.3,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/samsa-original.png\" class=\"attachment-full size-full wp-image-6024\" alt=\"\" srcset=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/samsa-original.png 500w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/samsa-original-300x300.png 300w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/samsa-original-150x150.png 150w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/samsa-original-370x370.png 370w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/samsa-original-90x90.png 90w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/samsa-original-410x410.png 410w\" sizes=\"(max-width: 767px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a0dbd2 e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"3a0dbd2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52e854b e-transform sc_fly_static elementor-widget elementor-widget-image\" data-id=\"52e854b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.3,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/parnasus-original.png\" class=\"attachment-full size-full wp-image-6023\" alt=\"\" srcset=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/parnasus-original.png 500w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/parnasus-original-300x300.png 300w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/parnasus-original-150x150.png 150w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/parnasus-original-370x370.png 370w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/parnasus-original-90x90.png 90w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/parnasus-original-410x410.png 410w\" sizes=\"(max-width: 767px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-893ce34 e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"893ce34\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8441c0e e-transform sc_fly_static elementor-widget elementor-widget-image\" data-id=\"8441c0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.3,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/la-negrita-png.png\" class=\"attachment-full size-full wp-image-6041\" alt=\"\" srcset=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/la-negrita-png.png 500w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/la-negrita-png-300x300.png 300w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/la-negrita-png-150x150.png 150w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/la-negrita-png-370x370.png 370w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/la-negrita-png-90x90.png 90w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/la-negrita-png-410x410.png 410w\" sizes=\"(max-width: 767px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ce28c05 e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"ce28c05\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8400782 e-transform sc_fly_static elementor-widget elementor-widget-image\" data-id=\"8400782\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.3,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/magazine-original.png\" class=\"attachment-full size-full wp-image-6022\" alt=\"\" srcset=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/magazine-original.png 500w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/magazine-original-300x300.png 300w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/magazine-original-150x150.png 150w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/magazine-original-370x370.png 370w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/magazine-original-90x90.png 90w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/magazine-original-410x410.png 410w\" sizes=\"(max-width: 767px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cba93d7 e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"cba93d7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-657c66b e-transform sc_fly_static elementor-widget elementor-widget-image\" data-id=\"657c66b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.3,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/gpw-original.png\" class=\"attachment-full size-full wp-image-6021\" alt=\"\" srcset=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/gpw-original.png 500w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/gpw-original-300x300.png 300w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/gpw-original-150x150.png 150w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/gpw-original-370x370.png 370w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/gpw-original-90x90.png 90w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/gpw-original-410x410.png 410w\" sizes=\"(max-width: 767px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7c885a0 e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"7c885a0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-046944c e-transform sc_fly_static elementor-widget elementor-widget-image\" data-id=\"046944c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.3,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/ica-logo.png\" class=\"attachment-full size-full wp-image-6042\" alt=\"\" srcset=\"https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/ica-logo.png 500w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/ica-logo-300x300.png 300w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/ica-logo-150x150.png 150w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/ica-logo-370x370.png 370w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/ica-logo-90x90.png 90w, https:\/\/bac-cia.com\/wp-content\/uploads\/2025\/07\/ica-logo-410x410.png 410w\" sizes=\"(max-width: 767px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3367abb e-flex e-con-boxed sc_layouts_column_icons_position_left e-con e-parent\" data-id=\"3367abb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8b1ee66 e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"8b1ee66\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div data-animation-type=\"block\" class=\"elementor-element elementor-element-05ffdf7 animation_type_block sc_fly_static elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"05ffdf7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;ta_fadeinup&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Your brand, well represented\n<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8d33660 e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"8d33660\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div data-animation-type=\"block\" class=\"elementor-element elementor-element-2941094 trx-addons-animate animation_type_block sc_fly_static elementor-invisible elementor-widget elementor-widget-trx_elm_advanced_title\" data-id=\"2941094\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;ta_fadeinup&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"trx_elm_advanced_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"trx-addons-advanced-title\" style=\"--var-trx-addons-advanced-title-highlight-animation-duration: 2000ms;\">\n<span class=\"trx-addons-advanced-title-item trx-addons-advanced-title-item-text elementor-repeater-item-eec72fe\">Your brand deserves legal backing for its \n<\/span>\n<span class=\"trx-addons-advanced-title-item trx-addons-advanced-title-item-text elementor-repeater-item-e308416 trx-addons-advanced-title-item-bg-as-text\">height.<\/span><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f4f084 sc_fly_static elementor-widget elementor-widget-button\" data-id=\"6f4f084\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/en\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">contact<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Menu Close ES ES EN FR&hellip;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"class_list":["post-5712","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/bac-cia.com\/en\/wp-json\/wp\/v2\/pages\/5712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bac-cia.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bac-cia.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bac-cia.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bac-cia.com\/en\/wp-json\/wp\/v2\/comments?post=5712"}],"version-history":[{"count":61,"href":"https:\/\/bac-cia.com\/en\/wp-json\/wp\/v2\/pages\/5712\/revisions"}],"predecessor-version":[{"id":6589,"href":"https:\/\/bac-cia.com\/en\/wp-json\/wp\/v2\/pages\/5712\/revisions\/6589"}],"wp:attachment":[{"href":"https:\/\/bac-cia.com\/en\/wp-json\/wp\/v2\/media?parent=5712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}